{"id":1391,"date":"2020-10-29T09:50:27","date_gmt":"2020-10-29T12:50:27","guid":{"rendered":"http:\/\/fbpf.org.br\/site\/?p=1391"},"modified":"2020-11-01T08:56:38","modified_gmt":"2020-11-01T11:56:38","slug":"3o-webnario-da-apfce","status":"publish","type":"post","link":"https:\/\/fbpf.org.br\/site\/evenements\/3o-webnario-da-apfce\/","title":{"rendered":"3\u00ba Webn\u00e1rio da APFCE"},"content":{"rendered":"\n<h5 class=\"wp-block-heading\"><strong>Choix Goncourt Br\u00e9sil e a literatura franc\u00f3fona da atualidade &#8211; experi\u00eancias de media\u00e7\u00e3o de leitura<\/strong><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">A Associa\u00e7\u00e3o de Professores de Franc\u00eas do Cear\u00e1 promove no dia 03 de novembro, \u00e0s 18.30, seu terceiro webn\u00e1rio de 2020. Na ocasi\u00e3o, discutiremos sobre experi\u00eancias de media\u00e7\u00e3o de leitura liter\u00e1ria.Ser\u00e1 um encontro remoto, via Meet.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">link para inscri\u00e7\u00e3o:&nbsp;<a rel=\"noreferrer noopener\" href=\"https:\/\/docs.google.com\/forms\/d\/e\/1FAIpQLSfAETx4hOCzXNkiyeiasqTzCf8MU2EnAvs0DQleIYznlXzE9w\/viewform\" target=\"_blank\">docs.google.com\/forms\/d\/e\/1FAIpQLSfAETx4hOCzXNkiyeiasqTzCf8MU2EnAvs0DQleIYznlXzE9w\/viewform<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Choix Goncourt Br\u00e9sil e a literatura franc\u00f3fona da atualidade \u2013 experi\u00eancias de media\u00e7\u00e3o de leitura<\/p>\n<p>A Associa\u00e7\u00e3o de Professores de Franc\u00eas do Cear\u00e1 promove no dia 03 de novembro, \u00e0s 18.30, seu terceiro webn\u00e1rio de 2020.<\/p>\n","protected":false},"author":2,"featured_media":1392,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18,6],"tags":[],"class_list":["post-1391","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ceara","category-evenements"],"featured_image_src":"https:\/\/fbpf.org.br\/site\/wp-content\/uploads\/2020\/10\/apfce_03-11-2020.jpg","author_info":{"display_name":"FBPF","author_link":"https:\/\/fbpf.org.br\/site\/author\/editor\/"},"_links":{"self":[{"href":"https:\/\/fbpf.org.br\/site\/wp-json\/wp\/v2\/posts\/1391","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fbpf.org.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fbpf.org.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fbpf.org.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/fbpf.org.br\/site\/wp-json\/wp\/v2\/comments?post=1391"}],"version-history":[{"count":2,"href":"https:\/\/fbpf.org.br\/site\/wp-json\/wp\/v2\/posts\/1391\/revisions"}],"predecessor-version":[{"id":1394,"href":"https:\/\/fbpf.org.br\/site\/wp-json\/wp\/v2\/posts\/1391\/revisions\/1394"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fbpf.org.br\/site\/wp-json\/wp\/v2\/media\/1392"}],"wp:attachment":[{"href":"https:\/\/fbpf.org.br\/site\/wp-json\/wp\/v2\/media?parent=1391"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fbpf.org.br\/site\/wp-json\/wp\/v2\/categories?post=1391"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fbpf.org.br\/site\/wp-json\/wp\/v2\/tags?post=1391"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}